{"id":5474,"date":"2026-02-12T09:49:32","date_gmt":"2026-02-12T09:49:32","guid":{"rendered":"https:\/\/truenmbstapp.de\/?post_type=help&#038;p=5474"},"modified":"2026-02-12T10:06:48","modified_gmt":"2026-02-12T10:06:48","slug":"how-to-cancel-a-subscription","status":"publish","type":"help","link":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/","title":{"rendered":"Como cancelar uma assinatura"},"content":{"rendered":"\n<p>O cancelamento da assinatura \u00e9 realizado de forma independente pelo servi\u00e7o por onde ela foi adquirida. Excluir o aplicativo ou sua conta n\u00e3o encerra uma assinatura ativa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Assinatura no Google Play<\/h3>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>No aplicativo Google Play, toque no \u00edcone de <strong>Conta<\/strong> no canto superior direito da tela.<\/li>\n\n\n\n<li>Selecione <strong>Pagamentos e assinaturas<\/strong> \u2192 <strong>Assinaturas<\/strong>.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full is-style-image-with-background\"><img decoding=\"async\" width=\"576\" height=\"1161\" loading=\"lazy\" src=\"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2026\/02\/paid05.webp\" alt=\"\" class=\"wp-image-5466\"\/><\/figure>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>Encontre o NumBuster na lista e toque em <strong>Cancelar assinatura<\/strong>.<\/li>\n\n\n\n<li>Se o Google sugerir pausar a assinatura, toque em <strong>N\u00e3o<\/strong> e confirme com o bot\u00e3o <strong>Cancelar assinatura<\/strong>.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">Painel WEB no site<\/h3>\n\n\n\n<p>Se voc\u00ea fez sua compra pelo site, o gerenciamento da assinatura ocorre em sua conta pessoal.<\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Abra o site <a href=\"https:\/\/app.numbuster.com\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>app.numbuster.com<\/strong><\/a> em seu navegador e fa\u00e7a login.<\/li>\n\n\n\n<li>Acesse a op\u00e7\u00e3o <strong>Recursos pagos<\/strong> (\u00edcone de carteira).<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full is-style-image-with-background\"><img decoding=\"async\" width=\"1170\" height=\"1123\" loading=\"lazy\" src=\"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2026\/02\/paid01-1.webp\" alt=\"\" class=\"wp-image-5329\"\/><\/figure>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>Clique no bot\u00e3o <strong>Desativar renova\u00e7\u00e3o<\/strong>.<\/li>\n\n\n\n<li>Se o bot\u00e3o <strong>Gerenciar pagamentos<\/strong> for exibido em vez disso, clique nele e selecione <strong>Cancelar plano<\/strong>.<\/li>\n<\/ol>\n\n\n\n<p><strong>Observa\u00e7\u00e3o:<\/strong> Se voc\u00ea j\u00e1 excluiu sua conta, entre em contato com o suporte. No e-mail, informe o n\u00famero de telefone para o qual a assinatura foi adquirida. Sua conta ser\u00e1 restaurada para que voc\u00ea possa cancelar a assinatura seguindo estas instru\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cancelamento da assinatura \u00e9 realizado de forma independente pelo servi\u00e7o por onde ela foi adquirida. Excluir o aplicativo ou sua conta n\u00e3o encerra uma assinatura ativa. Assinatura no Google Play Painel WEB no site Se voc\u00ea fez sua compra pelo site, o gerenciamento da assinatura ocorre em sua conta pessoal. Observa\u00e7\u00e3o: Se voc\u00ea j\u00e1 [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"help_category":[384,418],"help_platform":[],"class_list":["post-5474","help","type-help","status-publish","hentry","help_category-android","help_category-paid-features-android"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como cancelar uma assinatura - NumBuster<\/title>\n<meta name=\"description\" content=\"Como cancelar uma assinatura no NumBuster, onde \u00e9 gerenciado o renovamento e por que excluir a conta n\u00e3o encerra a assinatura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como cancelar uma assinatura - NumBuster\" \/>\n<meta property=\"og:description\" content=\"Como cancelar uma assinatura no NumBuster, onde \u00e9 gerenciado o renovamento e por que excluir a conta n\u00e3o encerra a assinatura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/\" \/>\n<meta property=\"og:site_name\" content=\"NumBuster\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T10:06:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2026\/02\/paid05.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/\",\"url\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/\",\"name\":\"Como cancelar uma assinatura - NumBuster\",\"isPartOf\":{\"@id\":\"https:\/\/numbuster.com\/tr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2026\/02\/paid05.webp\",\"datePublished\":\"2026-02-12T09:49:32+00:00\",\"dateModified\":\"2026-02-12T10:06:48+00:00\",\"description\":\"Como cancelar uma assinatura no NumBuster, onde \u00e9 gerenciado o renovamento e por que excluir a conta n\u00e3o encerra a assinatura.\",\"breadcrumb\":{\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/#primaryimage\",\"url\":\"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2026\/02\/paid05.webp\",\"contentUrl\":\"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2026\/02\/paid05.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/numbuster.me\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Central de Ajuda\",\"item\":\"https:\/\/numbustapp.com\/pt-pt\/help\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como cancelar uma assinatura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/#website\",\"url\":\"https:\/\/numbustapp.com\/pt-pt\",\"name\":\"NumBuster\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/numbuster.com\/tr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como cancelar uma assinatura - NumBuster","description":"Como cancelar uma assinatura no NumBuster, onde \u00e9 gerenciado o renovamento e por que excluir a conta n\u00e3o encerra a assinatura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/","og_locale":"pt_BR","og_type":"article","og_title":"Como cancelar uma assinatura - NumBuster","og_description":"Como cancelar uma assinatura no NumBuster, onde \u00e9 gerenciado o renovamento e por que excluir a conta n\u00e3o encerra a assinatura.","og_url":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/","og_site_name":"NumBuster","article_modified_time":"2026-02-12T10:06:48+00:00","og_image":[{"url":"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2026\/02\/paid05.webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/","url":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/","name":"Como cancelar uma assinatura - NumBuster","isPartOf":{"@id":"https:\/\/numbuster.com\/tr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/#primaryimage"},"image":{"@id":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/#primaryimage"},"thumbnailUrl":"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2026\/02\/paid05.webp","datePublished":"2026-02-12T09:49:32+00:00","dateModified":"2026-02-12T10:06:48+00:00","description":"Como cancelar uma assinatura no NumBuster, onde \u00e9 gerenciado o renovamento e por que excluir a conta n\u00e3o encerra a assinatura.","breadcrumb":{"@id":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/#primaryimage","url":"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2026\/02\/paid05.webp","contentUrl":"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2026\/02\/paid05.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/how-to-cancel-a-subscription\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/numbuster.me\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Central de Ajuda","item":"https:\/\/numbustapp.com\/pt-pt\/help\/"},{"@type":"ListItem","position":3,"name":"Como cancelar uma assinatura"}]},{"@type":"WebSite","@id":"https:\/\/numbustapp.com\/pt-pt\/#website","url":"https:\/\/numbustapp.com\/pt-pt","name":"NumBuster","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/numbuster.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/numbustapp.com\/pt-pt\/wp-json\/wp\/v2\/help\/5474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/numbustapp.com\/pt-pt\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/numbustapp.com\/pt-pt\/wp-json\/wp\/v2\/types\/help"}],"wp:attachment":[{"href":"https:\/\/numbustapp.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=5474"}],"wp:term":[{"taxonomy":"help_category","embeddable":true,"href":"https:\/\/numbustapp.com\/pt-pt\/wp-json\/wp\/v2\/help_category?post=5474"},{"taxonomy":"help_platform","embeddable":true,"href":"https:\/\/numbustapp.com\/pt-pt\/wp-json\/wp\/v2\/help_platform?post=5474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}