{"id":5376,"date":"2026-02-03T10:10:20","date_gmt":"2026-02-03T10:10:20","guid":{"rendered":"https:\/\/truenmbstapp.de\/?post_type=help&#038;p=5376"},"modified":"2026-02-03T10:26:19","modified_gmt":"2026-02-03T10:26:19","slug":"can-one-subscription-be-used-on-two-accounts","status":"publish","type":"help","link":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/","title":{"rendered":"\u00c9 poss\u00edvel usar uma assinatura em duas contas?"},"content":{"rendered":"\n<p>Uma \u00fanica compra n\u00e3o pode ser usada em duas contas diferentes simultaneamente. No entanto, voc\u00ea pode autorizar o uso da mesma conta em v\u00e1rios dispositivos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Como transferir uma assinatura para outra conta<\/h3>\n\n\n\n<p>Se voc\u00ea precisar transferir as fun\u00e7\u00f5es pagas para uma conta diferente, siga estas etapas. Voc\u00ea n\u00e3o precisa desinstalar o aplicativo para fazer isso.<\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Abra o menu de <strong>Configura\u00e7\u00f5es<\/strong> no aplicativo<\/li>\n\n\n\n<li>Toque no bot\u00e3o <strong>Sair<\/strong><\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full is-style-image-with-background\"><img decoding=\"async\" width=\"591\" height=\"816\" loading=\"lazy\" src=\"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2025\/08\/prof01.webp\" alt=\"\" class=\"wp-image-4314\"\/><\/figure>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>Autorize no formul\u00e1rio que aparece<\/li>\n<\/ol>\n\n\n\n<p><strong>Nota<\/strong>: ao autorizar via mensageiro, certifique-se de que o novo n\u00famero de telefone j\u00e1 esteja verificado no aplicativo de mensagens em seu dispositivo.<\/p>\n\n\n\n<p>Se voc\u00ea tiver algum problema durante a transfer\u00eancia, entre em contato com nossa equipe de suporte t\u00e9cnico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma \u00fanica compra n\u00e3o pode ser usada em duas contas diferentes simultaneamente. No entanto, voc\u00ea pode autorizar o uso da mesma conta em v\u00e1rios dispositivos. Como transferir uma assinatura para outra conta Se voc\u00ea precisar transferir as fun\u00e7\u00f5es pagas para uma conta diferente, siga estas etapas. Voc\u00ea n\u00e3o precisa desinstalar o aplicativo para fazer isso. [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"help_category":[384,418],"help_platform":[],"class_list":["post-5376","help","type-help","status-publish","hentry","help_category-android","help_category-paid-features-android"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9 poss\u00edvel usar uma assinatura em duas contas? - NumBuster<\/title>\n<meta name=\"description\" content=\"Uma assinatura do NumBuster funciona em apenas uma conta, com op\u00e7\u00e3o de transferir fun\u00e7\u00f5es pagas para outra conta se necess\u00e1rio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9 poss\u00edvel usar uma assinatura em duas contas? - NumBuster\" \/>\n<meta property=\"og:description\" content=\"Uma assinatura do NumBuster funciona em apenas uma conta, com op\u00e7\u00e3o de transferir fun\u00e7\u00f5es pagas para outra conta se necess\u00e1rio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/\" \/>\n<meta property=\"og:site_name\" content=\"NumBuster\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T10:26:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2025\/08\/prof01.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/\",\"url\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/\",\"name\":\"\u00c9 poss\u00edvel usar uma assinatura em duas contas? - NumBuster\",\"isPartOf\":{\"@id\":\"https:\/\/numbuster.com\/tr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2025\/08\/prof01.webp\",\"datePublished\":\"2026-02-03T10:10:20+00:00\",\"dateModified\":\"2026-02-03T10:26:19+00:00\",\"description\":\"Uma assinatura do NumBuster funciona em apenas uma conta, com op\u00e7\u00e3o de transferir fun\u00e7\u00f5es pagas para outra conta se necess\u00e1rio.\",\"breadcrumb\":{\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/#primaryimage\",\"url\":\"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2025\/08\/prof01.webp\",\"contentUrl\":\"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2025\/08\/prof01.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/numbuster.me\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Central de Ajuda\",\"item\":\"https:\/\/numbustapp.com\/pt-pt\/help\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9 poss\u00edvel usar uma assinatura em duas contas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/numbustapp.com\/pt-pt\/#website\",\"url\":\"https:\/\/numbustapp.com\/pt-pt\",\"name\":\"NumBuster\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/numbuster.com\/tr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9 poss\u00edvel usar uma assinatura em duas contas? - NumBuster","description":"Uma assinatura do NumBuster funciona em apenas uma conta, com op\u00e7\u00e3o de transferir fun\u00e7\u00f5es pagas para outra conta se necess\u00e1rio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/","og_locale":"pt_BR","og_type":"article","og_title":"\u00c9 poss\u00edvel usar uma assinatura em duas contas? - NumBuster","og_description":"Uma assinatura do NumBuster funciona em apenas uma conta, com op\u00e7\u00e3o de transferir fun\u00e7\u00f5es pagas para outra conta se necess\u00e1rio.","og_url":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/","og_site_name":"NumBuster","article_modified_time":"2026-02-03T10:26:19+00:00","og_image":[{"url":"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2025\/08\/prof01.webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/","url":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/","name":"\u00c9 poss\u00edvel usar uma assinatura em duas contas? - NumBuster","isPartOf":{"@id":"https:\/\/numbuster.com\/tr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/#primaryimage"},"image":{"@id":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/#primaryimage"},"thumbnailUrl":"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2025\/08\/prof01.webp","datePublished":"2026-02-03T10:10:20+00:00","dateModified":"2026-02-03T10:26:19+00:00","description":"Uma assinatura do NumBuster funciona em apenas uma conta, com op\u00e7\u00e3o de transferir fun\u00e7\u00f5es pagas para outra conta se necess\u00e1rio.","breadcrumb":{"@id":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/#primaryimage","url":"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2025\/08\/prof01.webp","contentUrl":"https:\/\/numbuster-wp-landing.s3.eu-north-1.amazonaws.com\/2025\/08\/prof01.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/numbustapp.com\/pt-pt\/help\/android\/paid-features-android\/can-one-subscription-be-used-on-two-accounts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/numbuster.me\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Central de Ajuda","item":"https:\/\/numbustapp.com\/pt-pt\/help\/"},{"@type":"ListItem","position":3,"name":"\u00c9 poss\u00edvel usar uma assinatura em duas contas?"}]},{"@type":"WebSite","@id":"https:\/\/numbustapp.com\/pt-pt\/#website","url":"https:\/\/numbustapp.com\/pt-pt","name":"NumBuster","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/numbuster.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/numbustapp.com\/pt-pt\/wp-json\/wp\/v2\/help\/5376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/numbustapp.com\/pt-pt\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/numbustapp.com\/pt-pt\/wp-json\/wp\/v2\/types\/help"}],"wp:attachment":[{"href":"https:\/\/numbustapp.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=5376"}],"wp:term":[{"taxonomy":"help_category","embeddable":true,"href":"https:\/\/numbustapp.com\/pt-pt\/wp-json\/wp\/v2\/help_category?post=5376"},{"taxonomy":"help_platform","embeddable":true,"href":"https:\/\/numbustapp.com\/pt-pt\/wp-json\/wp\/v2\/help_platform?post=5376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}